{"id":618,"date":"2019-05-07T12:57:55","date_gmt":"2019-05-07T12:57:55","guid":{"rendered":"https:\/\/tenerifecenter.dev-evocode.net\/services\/"},"modified":"2019-11-19T13:50:51","modified_gmt":"2019-11-19T13:50:51","slug":"servizi","status":"publish","type":"page","link":"https:\/\/alicantecenter.com\/it\/servizi\/","title":{"rendered":"Servizi"},"content":{"rendered":"under construction","protected":false},"excerpt":{"rendered":"<p>under construction<\/p>\n","protected":false},"author":1,"featured_media":256009,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-pages\/services-list.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-618","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Servizi immobiliari a Tenerife (Isole Canarie) - VYM Canarias<\/title>\n<meta name=\"description\" content=\"Vuoi comprare o vendere beni immobili a Tenerife (Spagna)? Ti aiuteremo a farlo con competenza e senza rischi! Una gamma completa di servizi dell&#039;agenzia VYM Canarias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/alicantecenter.com\/it\/servizi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servizi immobiliari a Tenerife (Isole Canarie) - VYM Canarias\" \/>\n<meta property=\"og:description\" content=\"Vuoi comprare o vendere beni immobili a Tenerife (Spagna)? Ti aiuteremo a farlo con competenza e senza rischi! Una gamma completa di servizi dell&#039;agenzia VYM Canarias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/alicantecenter.com\/it\/servizi\/\" \/>\n<meta property=\"og:site_name\" content=\"Alicante - VYM Canarias\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vym.canarias\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-19T13:50:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/alicantecenter.com\/wp-content\/uploads\/2019\/09\/vym-canarias-office-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/servizi\\\/\",\"url\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/servizi\\\/\",\"name\":\"Servizi immobiliari a Tenerife (Isole Canarie) - VYM Canarias\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/servizi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/servizi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/alicantecenter.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/vym-canarias-office-2.jpeg\",\"datePublished\":\"2019-05-07T12:57:55+00:00\",\"dateModified\":\"2019-11-19T13:50:51+00:00\",\"description\":\"Vuoi comprare o vendere beni immobili a Tenerife (Spagna)? Ti aiuteremo a farlo con competenza e senza rischi! Una gamma completa di servizi dell'agenzia VYM Canarias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/servizi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/alicantecenter.com\\\/it\\\/servizi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/servizi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/alicantecenter.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/vym-canarias-office-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/alicantecenter.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/vym-canarias-office-2.jpeg\",\"width\":1920,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/servizi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servizi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/\",\"name\":\"Alicante - VYM Canarias\",\"description\":\"Real Estate - Alicante\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/alicantecenter.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Servizi immobiliari a Tenerife (Isole Canarie) - VYM Canarias","description":"Vuoi comprare o vendere beni immobili a Tenerife (Spagna)? Ti aiuteremo a farlo con competenza e senza rischi! Una gamma completa di servizi dell'agenzia VYM Canarias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/alicantecenter.com\/it\/servizi\/","og_locale":"it_IT","og_type":"article","og_title":"Servizi immobiliari a Tenerife (Isole Canarie) - VYM Canarias","og_description":"Vuoi comprare o vendere beni immobili a Tenerife (Spagna)? Ti aiuteremo a farlo con competenza e senza rischi! Una gamma completa di servizi dell'agenzia VYM Canarias.","og_url":"https:\/\/alicantecenter.com\/it\/servizi\/","og_site_name":"Alicante - VYM Canarias","article_publisher":"https:\/\/www.facebook.com\/vym.canarias","article_modified_time":"2019-11-19T13:50:51+00:00","og_image":[{"width":1920,"height":350,"url":"https:\/\/alicantecenter.com\/wp-content\/uploads\/2019\/09\/vym-canarias-office-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/alicantecenter.com\/it\/servizi\/","url":"https:\/\/alicantecenter.com\/it\/servizi\/","name":"Servizi immobiliari a Tenerife (Isole Canarie) - VYM Canarias","isPartOf":{"@id":"https:\/\/alicantecenter.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/alicantecenter.com\/it\/servizi\/#primaryimage"},"image":{"@id":"https:\/\/alicantecenter.com\/it\/servizi\/#primaryimage"},"thumbnailUrl":"https:\/\/alicantecenter.com\/wp-content\/uploads\/2023\/06\/vym-canarias-office-2.jpeg","datePublished":"2019-05-07T12:57:55+00:00","dateModified":"2019-11-19T13:50:51+00:00","description":"Vuoi comprare o vendere beni immobili a Tenerife (Spagna)? Ti aiuteremo a farlo con competenza e senza rischi! Una gamma completa di servizi dell'agenzia VYM Canarias.","breadcrumb":{"@id":"https:\/\/alicantecenter.com\/it\/servizi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/alicantecenter.com\/it\/servizi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/alicantecenter.com\/it\/servizi\/#primaryimage","url":"https:\/\/alicantecenter.com\/wp-content\/uploads\/2023\/06\/vym-canarias-office-2.jpeg","contentUrl":"https:\/\/alicantecenter.com\/wp-content\/uploads\/2023\/06\/vym-canarias-office-2.jpeg","width":1920,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/alicantecenter.com\/it\/servizi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/alicantecenter.com\/it\/"},{"@type":"ListItem","position":2,"name":"Servizi"}]},{"@type":"WebSite","@id":"https:\/\/alicantecenter.com\/it\/#website","url":"https:\/\/alicantecenter.com\/it\/","name":"Alicante - VYM Canarias","description":"Real Estate - Alicante","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/alicantecenter.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/alicantecenter.com\/it\/wp-json\/wp\/v2\/pages\/618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alicantecenter.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/alicantecenter.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/alicantecenter.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/alicantecenter.com\/it\/wp-json\/wp\/v2\/comments?post=618"}],"version-history":[{"count":0,"href":"https:\/\/alicantecenter.com\/it\/wp-json\/wp\/v2\/pages\/618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alicantecenter.com\/it\/wp-json\/wp\/v2\/media\/256009"}],"wp:attachment":[{"href":"https:\/\/alicantecenter.com\/it\/wp-json\/wp\/v2\/media?parent=618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}